{"id":18699,"date":"2018-05-29T14:18:53","date_gmt":"2018-05-29T14:18:53","guid":{"rendered":"https:\/\/nimd.org\/empowering-a-local-leader-to-make-a-difference-in-georgia\/"},"modified":"2025-04-07T07:59:01","modified_gmt":"2025-04-07T07:59:01","slug":"empowering-a-local-leader-to-make-a-difference-in-georgia","status":"publish","type":"post","link":"https:\/\/nimd.org\/fr\/empowering-a-local-leader-to-make-a-difference-in-georgia\/","title":{"rendered":"Donner \u00e0 un dirigeant local les moyens de faire bouger les choses en G\u00e9orgie"},"content":{"rendered":"<p><em>Madona Batiashvili est la seule femme vice-maire de la r\u00e9gion de Kakheti en G\u00e9orgie.<\/em><\/p>\n<p><em>C'est une plateforme qu'elle utilise pour s'assurer que tout le monde a une voix. Nomm\u00e9e en 2017, elle a d'abord cherch\u00e9 \u00e0 impliquer et \u00e0 responsabiliser deux groupes souvent marginalis\u00e9s en G\u00e9orgie : les jeunes et les femmes.<\/em><\/p>\n<h3>L'\u00e9cole de la d\u00e9mocratie du NIMD<\/h3>\n<p>Madona est l'un des plus de 500 <a href=\"https:\/\/nimd.org\/fr\/democracy-school\/\" target=\"_blank\" rel=\"noopener\">\u00c9cole de la d\u00e9mocratie du NIMD<\/a> en G\u00e9orgie.<\/p>\n<p>Lorsqu'elle a rejoint l'\u00e9cole en 2016, elle s'est retrouv\u00e9e dans un creuset d'\u00e9tudiants issus d'horizons tr\u00e8s divers. Des fonctionnaires, des repr\u00e9sentants de la soci\u00e9t\u00e9 civile, des membres de partis politiques, des repr\u00e9sentants d'entreprises et des universitaires se r\u00e9unissent chaque ann\u00e9e \u00e0 l'\u00e9cole.<\/p>\n<p>Au cours de la p\u00e9riode de formation de cinq mois, ces participants approfondissent leur compr\u00e9hension des concepts cl\u00e9s de la d\u00e9mocratie, d\u00e9veloppent leur capacit\u00e9 d'analyse et acqui\u00e8rent des comp\u00e9tences pertinentes qui les aideront \u00e0 apporter des changements efficaces dans la soci\u00e9t\u00e9.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-6297\" src=\"http:\/\/nimd.org\/wp-content\/uploads\/2025\/02\/pullquote-1-new.png\" alt=\"\" width=\"580\" height=\"83\" \/><\/p>\n<p>Les quatre \u00e9coles de la d\u00e9mocratie de G\u00e9orgie - bas\u00e9es dans les villes de Telavi, Gori, Kutaisi et Batumi - jouent un r\u00f4le actif dans l'am\u00e9lioration de la culture politique et le renforcement des capacit\u00e9s de la soci\u00e9t\u00e9 civile et des dirigeants politiques au niveau local. C'est ce qui a incit\u00e9 Madona \u00e0 s'inscrire \u00e0 l'\u00e9cole de la d\u00e9mocratie : elle voulait apprendre aux c\u00f4t\u00e9s de personnes qui partageaient son ambition de changer les choses.<\/p>\n<figure id=\"attachment_6260\" aria-describedby=\"caption-attachment-6260\" style=\"width: 580px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-6260\" src=\"http:\/\/nimd.org\/wp-content\/uploads\/2025\/02\/certif-e1527603457936.jpg\" alt=\"\" width=\"580\" height=\"387\" \/><figcaption id=\"caption-attachment-6260\" class=\"wp-caption-text\">Madona est dipl\u00f4m\u00e9e de l'\u00e9cole de la d\u00e9mocratie.<\/figcaption><\/figure>\n<h3>Am\u00e9liorer les comp\u00e9tences et changer les perspectives<\/h3>\n<p>Lorsque Madona a commenc\u00e9 \u00e0 travailler \u00e0 l'\u00e9cole, elle a trouv\u00e9 difficile de travailler et d'apprendre avec des personnes d'appartenance politique diff\u00e9rente. Mais elle s'est vite rendu compte que l'interaction dans un tel environnement lui \u00e9tait b\u00e9n\u00e9fique. Les d\u00e9bats de l'\u00e9cole de la d\u00e9mocratie lui ont permis d'acqu\u00e9rir les comp\u00e9tences n\u00e9cessaires pour r\u00e9fl\u00e9chir \u00e0 ses propres arguments et tol\u00e9rer des opinions critiques et divergentes.<\/p>\n<p>Elle pense que ces comp\u00e9tences l'aident aujourd'hui lorsqu'elle doit persuader des coll\u00e8gues ou des adversaires de prendre certaines d\u00e9cisions :<\/p>\n<blockquote><p>\"Avant de fr\u00e9quenter l'\u00c9cole de la d\u00e9mocratie, je n'avais jamais eu l'occasion de travailler avec des personnes ayant des convictions politiques diff\u00e9rentes. Depuis que je suis \u00e0 l'\u00e9cole, je suis devenu plus tol\u00e9rant et plus sociable\".<\/p><\/blockquote>\n<h3>Promouvoir l'inclusion<\/h3>\n<p>Madona se souvient \u00e9galement que ses \u00e9tudes \u00e0 l'\u00e9cole lui ont fait prendre conscience de cette r\u00e9alit\u00e9 :<\/p>\n<blockquote><p>\"Un dirigeant contemporain a besoin d'\u00eatre cru par les gens. Nous avons besoin de plus d'ouverture et d'une rh\u00e9torique diff\u00e9rente\".<\/p><\/blockquote>\n<p>Cette nouvelle perspective a fait une diff\u00e9rence cruciale lorsqu'elle a commenc\u00e9 \u00e0 travailler dans un poste \u00e9lev\u00e9 de la fonction publique. Elle \u00e9tait d\u00e9termin\u00e9e \u00e0 s'ouvrir au public, \u00e0 combler le foss\u00e9 et \u00e0 appeler \u00e0 l'inclusion des diff\u00e9rents groupes qu'elle repr\u00e9sentait.<\/p>\n<p>En fait, l'une des premi\u00e8res actions de Madona en tant que vice-maire a \u00e9t\u00e9 d'\u00e9tablir des contacts avec les jeunes.<\/p>\n<p>L'engagement des jeunes dans l'autonomie locale est tr\u00e8s faible en G\u00e9orgie, et les jeunes sont souvent d\u00e9senchant\u00e9s par la politique. C'est pourquoi, apr\u00e8s avoir tendu la main aux jeunes de sa r\u00e9gion, Madona a entrepris d'apporter des modifications au budget local, en cr\u00e9ant des fonds pour les initiatives des organisations de jeunesse locales. Ces fonds prendront la forme de subventions, qui seront ouvertes aux demandes de toutes les organisations de jeunesse de la r\u00e9gion.<\/p>\n<p>Madona est convaincue que l'engagement des jeunes est essentiel pour assurer un avenir prosp\u00e8re \u00e0 sa r\u00e9gion. Elle esp\u00e8re que les nouveaux fonds aideront les jeunes \u00e0 s'engager dans la politique, \u00e0 r\u00e9aliser leur potentiel, \u00e0 trouver un emploi au niveau local et, en fin de compte, \u00e0 rester \u00e0 Kakheti.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-6259\" src=\"http:\/\/nimd.org\/wp-content\/uploads\/2025\/02\/27500910_773335346193555_3181743292021256954_o-e1527603520552.jpg\" alt=\"\" width=\"580\" height=\"386\" \/><\/p>\n<p>Un autre sujet qui tient \u00e0 c\u0153ur \u00e0 Madona, qui a fr\u00e9quent\u00e9 l'\u00e9cole de la d\u00e9mocratie, est celui des droits des femmes.<\/p>\n<p>La participation politique des femmes en G\u00e9orgie est alarmante. Les femmes ne d\u00e9tiennent que 16% des si\u00e8ges au Parlement de G\u00e9orgie, tandis que moins de 12-13% des \u00e9lus au niveau local sont des femmes. Les hommes dirigent 63 des 64 municipalit\u00e9s du pays, dont les huit de la r\u00e9gion de Kakheti.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-6292\" src=\"http:\/\/nimd.org\/wp-content\/uploads\/2025\/02\/pullquote-2-1-2.png\" alt=\"\" width=\"580\" height=\"53\" \/><\/p>\n<p>Dans ses nouvelles fonctions, Madona est d\u00e9termin\u00e9e \u00e0 faire de son mieux pour que les femmes actives et performantes aient la possibilit\u00e9 d'atteindre leur plein potentiel. Et elle a d\u00e9j\u00e0 pris des mesures pour que cela devienne une r\u00e9alit\u00e9.<\/p>\n<p>Pour tenter de compenser le grand nombre d'hommes en politique, Madona a recommand\u00e9 plusieurs femmes comme repr\u00e9sentantes du maire dans les villages. En faisant participer davantage de femmes \u00e0 ces fonctions locales, Madona esp\u00e8re leur donner une voix et les aider \u00e0 faire la diff\u00e9rence dans leurs communaut\u00e9s \u00e9galement.<\/p>\n<p>Le travail de Madona avec les jeunes et les femmes s'appuie sur une forte conviction, influenc\u00e9e par son passage \u00e0 l'\u00e9cole de la d\u00e9mocratie :<\/p>\n<blockquote><p>\"Il est important de comprendre que lorsque vous n'aimez pas la fa\u00e7on dont les choses fonctionnent, ou que vous n'\u00eates pas d'accord avec les d\u00e9cisions politiques de quelqu'un, vous devez commencer \u00e0 travailler pour changer ces d\u00e9cisions. Je suis heureux d'\u00eatre arriv\u00e9 \u00e0 cette conclusion, car je suis maintenant un fonctionnaire et je ferai tout ce que je peux pour am\u00e9liorer le fonctionnement de l'autonomie locale.<\/p><\/blockquote>\n<p>Madona est d\u00e9termin\u00e9e \u00e0 utiliser ce qu'elle a appris pour faire la diff\u00e9rence. Gr\u00e2ce aux \u00e9coles de la d\u00e9mocratie en G\u00e9orgie, l'objectif du NIMD, en collaboration avec notre partenaire, est d'am\u00e9liorer la qualit\u00e9 de l'enseignement. <a href=\"http:\/\/eecmd.org\/\" target=\"_blank\" rel=\"noopener\">EECMD<\/a> - est de permettre \u00e0 un plus grand nombre de personnes comme Madona de devenir des leaders dans leurs communaut\u00e9s et d'apporter des changements effectifs dans la soci\u00e9t\u00e9.<\/p>\n<p>&nbsp;<\/p>\n<p><em>En savoir plus sur les \u00e9coles de la d\u00e9mocratie du NIMD dans le monde\u00a0<a href=\"https:\/\/nimd.org\/fr\/democracy-school\/\" target=\"_blank\" rel=\"noopener\">ici<\/a>.<\/em><\/p>","protected":false},"excerpt":{"rendered":"<p>Madona Batiashvili est la seule femme vice-maire de la r\u00e9gion de Kakheti, en G\u00e9orgie. C'est une plateforme qu'elle utilise pour s'assurer que tout le monde a une voix. Ayant \u00e9t\u00e9 nomm\u00e9e en 2017, ses premi\u00e8res mesures dans ses fonctions ont \u00e9t\u00e9 d'engager et d'autonomiser deux groupes qui sont souvent marginalis\u00e9s de la politique en G\u00e9orgie : les jeunes et les femmes. Le programme D\u00e9mocratie du NIMD ... <a href=\"https:\/\/nimd.org\/fr\/empowering-a-local-leader-to-make-a-difference-in-georgia\/\"><\/a><\/p>","protected":false},"author":2,"featured_media":22282,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[113],"tags":[],"countries":[],"theme":[],"class_list":["post-18699","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-stories"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.5 (Yoast SEO v27.5) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Empowering a local leader to make a difference in Georgia - NIMD<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/nimd.org\/fr\/empowering-a-local-leader-to-make-a-difference-in-georgia\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Empowering a local leader to make a difference in Georgia\" \/>\n<meta property=\"og:description\" content=\"Madona Batiashvili is the only woman Vice-Mayor in Georgia\u2019s Kakheti region. It\u2019s a platform she uses to make sure everyone has a voice. Having been appointed in 2017, her first steps in office were to engage and empower two groups that are often marginalized from politics in Georgia: young people and women. The NIMD Democracy &hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/nimd.org\/fr\/empowering-a-local-leader-to-make-a-difference-in-georgia\/\" \/>\n<meta property=\"og:site_name\" content=\"NIMD\" \/>\n<meta property=\"article:published_time\" content=\"2018-05-29T14:18:53+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-04-07T07:59:01+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/nimd.org\/wp-content\/uploads\/2025\/02\/Madona.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"960\" \/>\n\t<meta property=\"og:image:height\" content=\"640\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"superadmin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"superadmin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/nimd.org\\\/fr\\\/empowering-a-local-leader-to-make-a-difference-in-georgia\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/nimd.org\\\/fr\\\/empowering-a-local-leader-to-make-a-difference-in-georgia\\\/\"},\"author\":{\"name\":\"superadmin\",\"@id\":\"https:\\\/\\\/nimd.org\\\/fr\\\/#\\\/schema\\\/person\\\/fecd680c201ede81b56eb098a17ad928\"},\"headline\":\"Empowering a local leader to make a difference in Georgia\",\"datePublished\":\"2018-05-29T14:18:53+00:00\",\"dateModified\":\"2025-04-07T07:59:01+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/nimd.org\\\/fr\\\/empowering-a-local-leader-to-make-a-difference-in-georgia\\\/\"},\"wordCount\":825,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/nimd.org\\\/fr\\\/empowering-a-local-leader-to-make-a-difference-in-georgia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/nimd.org\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/Madona.jpg\",\"articleSection\":[\"Stories\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/nimd.org\\\/fr\\\/empowering-a-local-leader-to-make-a-difference-in-georgia\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/nimd.org\\\/fr\\\/empowering-a-local-leader-to-make-a-difference-in-georgia\\\/\",\"url\":\"https:\\\/\\\/nimd.org\\\/fr\\\/empowering-a-local-leader-to-make-a-difference-in-georgia\\\/\",\"name\":\"Empowering a local leader to make a difference in Georgia - NIMD\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/nimd.org\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/nimd.org\\\/fr\\\/empowering-a-local-leader-to-make-a-difference-in-georgia\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/nimd.org\\\/fr\\\/empowering-a-local-leader-to-make-a-difference-in-georgia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/nimd.org\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/Madona.jpg\",\"datePublished\":\"2018-05-29T14:18:53+00:00\",\"dateModified\":\"2025-04-07T07:59:01+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/nimd.org\\\/fr\\\/#\\\/schema\\\/person\\\/fecd680c201ede81b56eb098a17ad928\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/nimd.org\\\/fr\\\/empowering-a-local-leader-to-make-a-difference-in-georgia\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/nimd.org\\\/fr\\\/empowering-a-local-leader-to-make-a-difference-in-georgia\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/nimd.org\\\/fr\\\/empowering-a-local-leader-to-make-a-difference-in-georgia\\\/#primaryimage\",\"url\":\"https:\\\/\\\/nimd.org\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/Madona.jpg\",\"contentUrl\":\"https:\\\/\\\/nimd.org\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/Madona.jpg\",\"width\":960,\"height\":640},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/nimd.org\\\/fr\\\/empowering-a-local-leader-to-make-a-difference-in-georgia\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/nimd.org\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Empowering a local leader to make a difference in Georgia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/nimd.org\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/nimd.org\\\/fr\\\/\",\"name\":\"NIMD\",\"description\":\"Democracy Starts With Dialogue\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/nimd.org\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/nimd.org\\\/fr\\\/#\\\/schema\\\/person\\\/fecd680c201ede81b56eb098a17ad928\",\"name\":\"superadmin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1d1e7ebaf312b717161d349f71f6060e0ed86d7a652cbc37adc644a79988d181?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1d1e7ebaf312b717161d349f71f6060e0ed86d7a652cbc37adc644a79988d181?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1d1e7ebaf312b717161d349f71f6060e0ed86d7a652cbc37adc644a79988d181?s=96&d=mm&r=g\",\"caption\":\"superadmin\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Donner \u00e0 un dirigeant local les moyens de faire la diff\u00e9rence en G\u00e9orgie - NIMD","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/nimd.org\/fr\/empowering-a-local-leader-to-make-a-difference-in-georgia\/","og_locale":"fr_FR","og_type":"article","og_title":"Empowering a local leader to make a difference in Georgia","og_description":"Madona Batiashvili is the only woman Vice-Mayor in Georgia\u2019s Kakheti region. It\u2019s a platform she uses to make sure everyone has a voice. Having been appointed in 2017, her first steps in office were to engage and empower two groups that are often marginalized from politics in Georgia: young people and women. The NIMD Democracy &hellip;","og_url":"https:\/\/nimd.org\/fr\/empowering-a-local-leader-to-make-a-difference-in-georgia\/","og_site_name":"NIMD","article_published_time":"2018-05-29T14:18:53+00:00","article_modified_time":"2025-04-07T07:59:01+00:00","og_image":[{"width":960,"height":640,"url":"https:\/\/nimd.org\/wp-content\/uploads\/2025\/02\/Madona.jpg","type":"image\/jpeg"}],"author":"superadmin","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"superadmin","Dur\u00e9e de lecture estim\u00e9e":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/nimd.org\/fr\/empowering-a-local-leader-to-make-a-difference-in-georgia\/#article","isPartOf":{"@id":"https:\/\/nimd.org\/fr\/empowering-a-local-leader-to-make-a-difference-in-georgia\/"},"author":{"name":"superadmin","@id":"https:\/\/nimd.org\/fr\/#\/schema\/person\/fecd680c201ede81b56eb098a17ad928"},"headline":"Empowering a local leader to make a difference in Georgia","datePublished":"2018-05-29T14:18:53+00:00","dateModified":"2025-04-07T07:59:01+00:00","mainEntityOfPage":{"@id":"https:\/\/nimd.org\/fr\/empowering-a-local-leader-to-make-a-difference-in-georgia\/"},"wordCount":825,"commentCount":0,"image":{"@id":"https:\/\/nimd.org\/fr\/empowering-a-local-leader-to-make-a-difference-in-georgia\/#primaryimage"},"thumbnailUrl":"https:\/\/nimd.org\/wp-content\/uploads\/2025\/02\/Madona.jpg","articleSection":["Stories"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/nimd.org\/fr\/empowering-a-local-leader-to-make-a-difference-in-georgia\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/nimd.org\/fr\/empowering-a-local-leader-to-make-a-difference-in-georgia\/","url":"https:\/\/nimd.org\/fr\/empowering-a-local-leader-to-make-a-difference-in-georgia\/","name":"Donner \u00e0 un dirigeant local les moyens de faire la diff\u00e9rence en G\u00e9orgie - NIMD","isPartOf":{"@id":"https:\/\/nimd.org\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/nimd.org\/fr\/empowering-a-local-leader-to-make-a-difference-in-georgia\/#primaryimage"},"image":{"@id":"https:\/\/nimd.org\/fr\/empowering-a-local-leader-to-make-a-difference-in-georgia\/#primaryimage"},"thumbnailUrl":"https:\/\/nimd.org\/wp-content\/uploads\/2025\/02\/Madona.jpg","datePublished":"2018-05-29T14:18:53+00:00","dateModified":"2025-04-07T07:59:01+00:00","author":{"@id":"https:\/\/nimd.org\/fr\/#\/schema\/person\/fecd680c201ede81b56eb098a17ad928"},"breadcrumb":{"@id":"https:\/\/nimd.org\/fr\/empowering-a-local-leader-to-make-a-difference-in-georgia\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/nimd.org\/fr\/empowering-a-local-leader-to-make-a-difference-in-georgia\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/nimd.org\/fr\/empowering-a-local-leader-to-make-a-difference-in-georgia\/#primaryimage","url":"https:\/\/nimd.org\/wp-content\/uploads\/2025\/02\/Madona.jpg","contentUrl":"https:\/\/nimd.org\/wp-content\/uploads\/2025\/02\/Madona.jpg","width":960,"height":640},{"@type":"BreadcrumbList","@id":"https:\/\/nimd.org\/fr\/empowering-a-local-leader-to-make-a-difference-in-georgia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/nimd.org\/fr\/"},{"@type":"ListItem","position":2,"name":"Empowering a local leader to make a difference in Georgia"}]},{"@type":"WebSite","@id":"https:\/\/nimd.org\/fr\/#website","url":"https:\/\/nimd.org\/fr\/","name":"NIMD","description":"La d\u00e9mocratie commence par le dialogue","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/nimd.org\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/nimd.org\/fr\/#\/schema\/person\/fecd680c201ede81b56eb098a17ad928","name":"superadministrateur","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/1d1e7ebaf312b717161d349f71f6060e0ed86d7a652cbc37adc644a79988d181?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/1d1e7ebaf312b717161d349f71f6060e0ed86d7a652cbc37adc644a79988d181?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/1d1e7ebaf312b717161d349f71f6060e0ed86d7a652cbc37adc644a79988d181?s=96&d=mm&r=g","caption":"superadmin"}}]}},"_links":{"self":[{"href":"https:\/\/nimd.org\/fr\/wp-json\/wp\/v2\/posts\/18699","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nimd.org\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nimd.org\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nimd.org\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/nimd.org\/fr\/wp-json\/wp\/v2\/comments?post=18699"}],"version-history":[{"count":5,"href":"https:\/\/nimd.org\/fr\/wp-json\/wp\/v2\/posts\/18699\/revisions"}],"predecessor-version":[{"id":24521,"href":"https:\/\/nimd.org\/fr\/wp-json\/wp\/v2\/posts\/18699\/revisions\/24521"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nimd.org\/fr\/wp-json\/wp\/v2\/media\/22282"}],"wp:attachment":[{"href":"https:\/\/nimd.org\/fr\/wp-json\/wp\/v2\/media?parent=18699"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nimd.org\/fr\/wp-json\/wp\/v2\/categories?post=18699"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nimd.org\/fr\/wp-json\/wp\/v2\/tags?post=18699"},{"taxonomy":"countries","embeddable":true,"href":"https:\/\/nimd.org\/fr\/wp-json\/wp\/v2\/countries?post=18699"},{"taxonomy":"theme","embeddable":true,"href":"https:\/\/nimd.org\/fr\/wp-json\/wp\/v2\/theme?post=18699"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}