{"id":18984,"date":"2021-12-06T08:30:59","date_gmt":"2021-12-06T08:30:59","guid":{"rendered":"https:\/\/nimd.org\/mozambique-using-dialogue-in-the-fight-against-climate-change\/"},"modified":"2025-04-07T08:13:38","modified_gmt":"2025-04-07T08:13:38","slug":"mozambique-using-dialogue-in-the-fight-against-climate-change","status":"publish","type":"post","link":"https:\/\/nimd.org\/es\/mozambique-using-dialogue-in-the-fight-against-climate-change\/","title":{"rendered":"Mozambique: Utilizar el di\u00e1logo en la lucha contra el cambio clim\u00e1tico"},"content":{"rendered":"<p><em>La reciente Cumbre COP26 de Glasgow suscit\u00f3 un debate sobre el papel de la democracia en la lucha contra el cambio clim\u00e1tico. Aqu\u00ed, <strong>H<\/strong><\/em><em><strong>ermenegildo<\/strong><\/em><em><strong>\u00a0Mulhovo<\/strong>Director Ejecutivo de la <a href=\"https:\/\/www.imd.org.mz\/\" target=\"_blank\" rel=\"noopener\">Instituto para la Democracia Multipartidista (IMD)<\/a> y socio de NIMD en Mozambique, sostiene que la democracia es el \u00fanico sistema que puede hacer frente al desaf\u00edo.<\/em><\/p>\n<p>En muchos sentidos, el Planeta Tierra es el proyecto democr\u00e1tico por excelencia. Cada persona que vive en \u00e9l tiene un inter\u00e9s en su futuro. A pesar de los esfuerzos por parcelar sus tierras, imponer fronteras en sus mares y dividir su atm\u00f3sfera en espacios a\u00e9reos, no cabe duda de que el aire que respiramos y la naturaleza que nos rodea est\u00e1n ah\u00ed en beneficio de todos.<\/p>\n<p>Y sin embargo, cuando los l\u00edderes mundiales se re\u00fanen en cumbres como la <a href=\"https:\/\/www.bbc.com\/news\/science-environment-56901261\" target=\"_blank\" rel=\"noopener\">reciente COP26 en Glasgow<\/a>Sin embargo, el debate puede parecer distante, y es dif\u00edcil sentir que tenemos algo que decir en las discusiones. Esto puede ser especialmente frustrante para las personas que se enfrentan a los efectos m\u00e1s graves del cambio clim\u00e1tico, que a menudo viven en naciones m\u00e1s peque\u00f1as o menos desarrolladas, lo que amplifica esa sensaci\u00f3n de impotencia.<\/p>\n<figure id=\"attachment_12384\" aria-describedby=\"caption-attachment-12384\" style=\"width: 570px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-12384\" src=\"http:\/\/nimd.org\/wp-content\/uploads\/2025\/02\/UN744718_d8b_.jpg\" alt=\"Women in Mozambique wait at the UN clinic\" width=\"570\" height=\"380\" \/><figcaption id=\"caption-attachment-12384\" class=\"wp-caption-text\">Mujeres de Mozambique esperan frente a una cl\u00ednica de la ONU<\/figcaption><\/figure>\n<p>Esta sensaci\u00f3n de inmenso desaf\u00edo global que requiere medidas r\u00e1pidas y radicales tambi\u00e9n ha hecho que algunos grupos de la sociedad se pregunten si deben aplicarse los procedimientos democr\u00e1ticos. Tal vez, sugieren, la escala y la urgencia de la situaci\u00f3n justifiquen la suspensi\u00f3n de algunos de los procesos democr\u00e1ticos normales.<\/p>\n<p>Pero creo que es justo lo contrario: la democracia es vital en la lucha contra el cambio clim\u00e1tico. A menos que la gente se sienta parte del proceso y participe en las soluciones, hay pocas esperanzas de \u00e9xito.<\/p>\n<p>En Mozambique, tuvimos hace unos a\u00f1os un ejemplo estremecedor del efecto directo que el cambio clim\u00e1tico puede tener en la democracia. En marzo de 2019, el cicl\u00f3n Idai devast\u00f3 franjas del pa\u00eds. Fue el cicl\u00f3n m\u00e1s fuerte registrado en el sur de \u00c1frica, y Mozambique es ahora reconocido como <a href=\"https:\/\/www.thenewhumanitarian.org\/analysis\/2021\/11\/1\/four-ways-Mozambique-is-adapting-to-the-climate-crisis\" target=\"_blank\" rel=\"noopener\">uno de los pa\u00edses m\u00e1s afectados<\/a> por fen\u00f3menos meteorol\u00f3gicos extremos relacionados con el calentamiento global.<\/p>\n<figure id=\"attachment_12386\" aria-describedby=\"caption-attachment-12386\" style=\"width: 580px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-12386\" src=\"http:\/\/nimd.org\/wp-content\/uploads\/2025\/02\/UN744525_cca_.jpg\" alt=\"A classroom in Mozambique damaged by Cyclones Idai and Kenneth\" width=\"580\" height=\"387\" \/><figcaption id=\"caption-attachment-12386\" class=\"wp-caption-text\">Tras el cicl\u00f3n, las escuelas destinadas a ser utilizadas como colegios electorales sufrieron da\u00f1os.<\/figcaption><\/figure>\n<p>Siete meses despu\u00e9s del cicl\u00f3n Idai, celebramos elecciones generales. El desplazamiento masivo de decenas de miles de personas hab\u00eda desorganizado el censo electoral. Las escuelas que deb\u00edan ser centros de votaci\u00f3n estaban destruidas o se utilizaban para alojar a los desplazados. Esta sensaci\u00f3n de caos cre\u00f3 un espacio para que algunos actores pol\u00edticos manipularan la crisis, con informes de fraude electoral y acusaciones de corrupci\u00f3n y malversaci\u00f3n de la ayuda.<\/p>\n<p>Las elecciones se celebraron, pero muchos consideraron que los acontecimientos que precedieron a los comicios empa\u00f1aron su legitimidad, y este malestar ensombrece hoy nuestra democracia.<\/p>\n<h3><strong>Incluir a todos en el debate<\/strong><\/h3>\n<p>Desde entonces, nuestro Instituto para la Democracia Multipartidista, en colaboraci\u00f3n con el NIMD, ha hecho del cambio clim\u00e1tico y el medio ambiente una de las principales prioridades de nuestro trabajo.<\/p>\n<p>Siempre nos hemos esforzado por promover el di\u00e1logo sobre las normas en las industrias extractivas, pero mientras que en el pasado nos centr\u00e1bamos en la gobernanza y la transparencia, ahora nos estamos centrando tambi\u00e9n en el impacto medioambiental.<\/p>\n<figure id=\"attachment_12385\" aria-describedby=\"caption-attachment-12385\" style=\"width: 580px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-12385\" src=\"http:\/\/nimd.org\/wp-content\/uploads\/2025\/02\/UN744783_dcc_.jpg\" alt=\"Damage in Mozambique from Cyclones Idai and Kenneth\" width=\"580\" height=\"387\" \/><figcaption id=\"caption-attachment-12385\" class=\"wp-caption-text\">Da\u00f1os causados por el cicl\u00f3n Idai en la ciudad de Beira.<\/figcaption><\/figure>\n<p>El 22 de noviembre reunimos a representantes de la sociedad civil, el gobierno, los partidos pol\u00edticos y la comunidad internacional para <a href=\"https:\/\/www.imd.org.mz\/index.php\/imprensa\/noticias\/429-industria-extractiva-deve-contribuir-para-desenvolvimento-do-capital-humano\" target=\"_blank\" rel=\"noopener\">una conferencia de dos d\u00edas<\/a> sobre las industrias extractivas. Personas de todos los \u00e1mbitos pol\u00edticos y de la sociedad civil se reunieron para debatir el equilibrio entre explotar los recursos y garantizar la sostenibilidad medioambiental.<\/p>\n<p>Entre los temas de la conferencia figuraban el papel del g\u00e9nero en las industrias extractivas y la importancia de garantizar un reparto equitativo de los beneficios de la explotaci\u00f3n de los recursos.<\/p>\n<blockquote><p>\"La democracia crea el espacio para que se produzca el consenso, lo que conduce a decisiones significativas que tienen un impacto duradero\".<\/p><\/blockquote>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignright wp-image-12393\" src=\"http:\/\/nimd.org\/wp-content\/uploads\/2025\/02\/extractive_industries_poster-copy.jpg\" alt=\"Poster for extractive industries conference\" width=\"300\" height=\"384\" \/><\/p>\n<p>Esta inclusividad es clave: si la gente se siente excluida del di\u00e1logo sobre el cambio clim\u00e1tico, no sentir\u00e1 ninguna conexi\u00f3n con las soluciones.<\/p>\n<p>Por ejemplo, aqu\u00ed en Mozambique hay algunas antiguas pr\u00e1cticas agr\u00edcolas y pesqueras que ahora nos damos cuenta de que son perjudiciales para el medio ambiente. Sin embargo, algunas familias siguen practic\u00e1ndolas porque su sustento depende de ellas. Aparecer y simplemente decirles que dejen de hacerlo tendr\u00eda poco impacto. Siempre que se impone, nadie tiene la propiedad.<\/p>\n<p>Al garantizar la participaci\u00f3n de grupos de la sociedad civil en los debates de alto nivel, nos aseguramos de que se escuche la voz de todos.<\/p>\n<p>Tiene que ser un debate igualitario en el que encontremos un entendimiento com\u00fan sobre c\u00f3mo podemos proteger juntos la naturaleza para garantizar todos nuestros medios de vida en el futuro.<\/p>\n<p>La democracia crea el espacio para que se produzca este consenso, dando lugar a decisiones significativas que tienen un impacto duradero.<\/p>\n<p>La creaci\u00f3n de plataformas neutrales para estas interacciones integradoras entre la poblaci\u00f3n, las organizaciones de la sociedad civil y el gobierno es fundamental. En el pasado, daba la sensaci\u00f3n de que hab\u00eda una brecha, con los responsables pol\u00edticos a un lado y la sociedad civil al otro, y cualquier interacci\u00f3n sol\u00eda ser una confrontaci\u00f3n. Esto no consigue resultados duraderos.<\/p>\n<figure id=\"attachment_12465\" aria-describedby=\"caption-attachment-12465\" style=\"width: 580px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-12465\" src=\"http:\/\/nimd.org\/wp-content\/uploads\/2025\/04\/extractive_industries_conference-300x199.jpg\" alt=\"Hermenegildo Mulhovo addressing a conference. \" width=\"580\" height=\"384\" \/><figcaption id=\"caption-attachment-12465\" class=\"wp-caption-text\">Hermenegildo Mulhovo interviene en la Conferencia sobre Extractivas<\/figcaption><\/figure>\n<p>As\u00ed que tenemos que facilitar el acceso entre la sociedad civil y los responsables de la toma de decisiones en un entorno no conflictivo, para que puedan influirse mutuamente y trabajar juntos. Todos los partidos pol\u00edticos deben participar tambi\u00e9n en este di\u00e1logo, aceptando que deben colaborar por encima de las l\u00edneas partidistas por un bien mayor.<\/p>\n<p>Esto se repite tambi\u00e9n a nivel mundial. Muchos de los l\u00edderes antidemocr\u00e1ticos que vemos hoy en todo el mundo defienden pol\u00edticas nacionalistas y encerradas en s\u00ed mismas. Pero necesitamos la cooperaci\u00f3n mundial y el multilateralismo si queremos abordar los inmensos retos a los que nos enfrentamos.<\/p>\n<p>As\u00ed que aprovechemos este momento y volvamos a comprometernos con los valores de la inclusi\u00f3n y la democracia. Ahora es el momento de ser audaces y valientes, y defender y promover el \u00fanico sistema que nos ayudar\u00e1 a guiarnos a todos hacia un futuro mejor.<\/p>\n<p>&nbsp;<\/p>","protected":false},"excerpt":{"rendered":"<p>La reciente Cumbre COP26 celebrada en Glasgow suscit\u00f3 un debate sobre el papel de la democracia en la lucha contra el cambio clim\u00e1tico. Aqu\u00ed, Hermenegildo Mulhovo, Director Ejecutivo del Instituto para la Democracia Multipartidista (IMD) y socio de NIMD en Mozambique, sostiene que la democracia es el \u00fanico sistema que puede hacer frente al desaf\u00edo. En muchos sentidos, el planeta Tierra es el ... <a href=\"https:\/\/nimd.org\/es\/mozambique-using-dialogue-in-the-fight-against-climate-change\/\"><\/a><\/p>","protected":false},"author":2,"featured_media":25010,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[149],"tags":[],"countries":[90],"theme":[69],"class_list":["post-18984","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-opinion-analysis","countries-mozambique","theme-dialogue"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.5 (Yoast SEO v27.5) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Mozambique: Using dialogue in the fight against climate change - NIMD<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/nimd.org\/es\/mozambique-using-dialogue-in-the-fight-against-climate-change\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mozambique: Using dialogue in the fight against climate change\" \/>\n<meta property=\"og:description\" content=\"The recent COP26 Summit in Glasgow prompted debate about the role of democracy in the fight against climate change. Here, Hermenegildo\u00a0Mulhovo, Executive Director of the Institute for Multiparty Democracy (IMD) and NIMD\u2019s partner in Mozambique, argues that democracy is the only system that can meet the challenge. In many ways, Planet Earth is the ultimate &hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/nimd.org\/es\/mozambique-using-dialogue-in-the-fight-against-climate-change\/\" \/>\n<meta property=\"og:site_name\" content=\"NIMD\" \/>\n<meta property=\"article:published_time\" content=\"2021-12-06T08:30:59+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-04-07T08:13:38+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/nimd.org\/wp-content\/uploads\/2025\/04\/UN744657_d4e_.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"superadmin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"superadmin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/nimd.org\\\/mozambique-using-dialogue-in-the-fight-against-climate-change\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/nimd.org\\\/mozambique-using-dialogue-in-the-fight-against-climate-change\\\/\"},\"author\":{\"name\":\"superadmin\",\"@id\":\"https:\\\/\\\/nimd.org\\\/fr\\\/#\\\/schema\\\/person\\\/fecd680c201ede81b56eb098a17ad928\"},\"headline\":\"Mozambique: Using dialogue in the fight against climate change\",\"datePublished\":\"2021-12-06T08:30:59+00:00\",\"dateModified\":\"2025-04-07T08:13:38+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/nimd.org\\\/mozambique-using-dialogue-in-the-fight-against-climate-change\\\/\"},\"wordCount\":954,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/nimd.org\\\/mozambique-using-dialogue-in-the-fight-against-climate-change\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/nimd.org\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/UN744657_d4e_.jpg\",\"articleSection\":[\"Opinion &amp; analysis\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/nimd.org\\\/mozambique-using-dialogue-in-the-fight-against-climate-change\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/nimd.org\\\/mozambique-using-dialogue-in-the-fight-against-climate-change\\\/\",\"url\":\"https:\\\/\\\/nimd.org\\\/mozambique-using-dialogue-in-the-fight-against-climate-change\\\/\",\"name\":\"Mozambique: Using dialogue in the fight against climate change - NIMD\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/nimd.org\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/nimd.org\\\/mozambique-using-dialogue-in-the-fight-against-climate-change\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/nimd.org\\\/mozambique-using-dialogue-in-the-fight-against-climate-change\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/nimd.org\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/UN744657_d4e_.jpg\",\"datePublished\":\"2021-12-06T08:30:59+00:00\",\"dateModified\":\"2025-04-07T08:13:38+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/nimd.org\\\/fr\\\/#\\\/schema\\\/person\\\/fecd680c201ede81b56eb098a17ad928\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/nimd.org\\\/mozambique-using-dialogue-in-the-fight-against-climate-change\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/nimd.org\\\/mozambique-using-dialogue-in-the-fight-against-climate-change\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/nimd.org\\\/mozambique-using-dialogue-in-the-fight-against-climate-change\\\/#primaryimage\",\"url\":\"https:\\\/\\\/nimd.org\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/UN744657_d4e_.jpg\",\"contentUrl\":\"https:\\\/\\\/nimd.org\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/UN744657_d4e_.jpg\",\"width\":1200,\"height\":800},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/nimd.org\\\/mozambique-using-dialogue-in-the-fight-against-climate-change\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/nimd.org\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mozambique: Using dialogue in the fight against climate change\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/nimd.org\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/nimd.org\\\/fr\\\/\",\"name\":\"NIMD\",\"description\":\"Democracy Starts With Dialogue\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/nimd.org\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/nimd.org\\\/fr\\\/#\\\/schema\\\/person\\\/fecd680c201ede81b56eb098a17ad928\",\"name\":\"superadmin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1d1e7ebaf312b717161d349f71f6060e0ed86d7a652cbc37adc644a79988d181?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1d1e7ebaf312b717161d349f71f6060e0ed86d7a652cbc37adc644a79988d181?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1d1e7ebaf312b717161d349f71f6060e0ed86d7a652cbc37adc644a79988d181?s=96&d=mm&r=g\",\"caption\":\"superadmin\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Mozambique: Utilizar el di\u00e1logo en la lucha contra el cambio clim\u00e1tico - NIMD","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/nimd.org\/es\/mozambique-using-dialogue-in-the-fight-against-climate-change\/","og_locale":"es_ES","og_type":"article","og_title":"Mozambique: Using dialogue in the fight against climate change","og_description":"The recent COP26 Summit in Glasgow prompted debate about the role of democracy in the fight against climate change. Here, Hermenegildo\u00a0Mulhovo, Executive Director of the Institute for Multiparty Democracy (IMD) and NIMD\u2019s partner in Mozambique, argues that democracy is the only system that can meet the challenge. In many ways, Planet Earth is the ultimate &hellip;","og_url":"https:\/\/nimd.org\/es\/mozambique-using-dialogue-in-the-fight-against-climate-change\/","og_site_name":"NIMD","article_published_time":"2021-12-06T08:30:59+00:00","article_modified_time":"2025-04-07T08:13:38+00:00","og_image":[{"width":1200,"height":800,"url":"https:\/\/nimd.org\/wp-content\/uploads\/2025\/04\/UN744657_d4e_.jpg","type":"image\/jpeg"}],"author":"superadmin","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"superadmin","Tiempo de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/nimd.org\/mozambique-using-dialogue-in-the-fight-against-climate-change\/#article","isPartOf":{"@id":"https:\/\/nimd.org\/mozambique-using-dialogue-in-the-fight-against-climate-change\/"},"author":{"name":"superadmin","@id":"https:\/\/nimd.org\/fr\/#\/schema\/person\/fecd680c201ede81b56eb098a17ad928"},"headline":"Mozambique: Using dialogue in the fight against climate change","datePublished":"2021-12-06T08:30:59+00:00","dateModified":"2025-04-07T08:13:38+00:00","mainEntityOfPage":{"@id":"https:\/\/nimd.org\/mozambique-using-dialogue-in-the-fight-against-climate-change\/"},"wordCount":954,"commentCount":0,"image":{"@id":"https:\/\/nimd.org\/mozambique-using-dialogue-in-the-fight-against-climate-change\/#primaryimage"},"thumbnailUrl":"https:\/\/nimd.org\/wp-content\/uploads\/2025\/04\/UN744657_d4e_.jpg","articleSection":["Opinion &amp; analysis"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/nimd.org\/mozambique-using-dialogue-in-the-fight-against-climate-change\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/nimd.org\/mozambique-using-dialogue-in-the-fight-against-climate-change\/","url":"https:\/\/nimd.org\/mozambique-using-dialogue-in-the-fight-against-climate-change\/","name":"Mozambique: Utilizar el di\u00e1logo en la lucha contra el cambio clim\u00e1tico - NIMD","isPartOf":{"@id":"https:\/\/nimd.org\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/nimd.org\/mozambique-using-dialogue-in-the-fight-against-climate-change\/#primaryimage"},"image":{"@id":"https:\/\/nimd.org\/mozambique-using-dialogue-in-the-fight-against-climate-change\/#primaryimage"},"thumbnailUrl":"https:\/\/nimd.org\/wp-content\/uploads\/2025\/04\/UN744657_d4e_.jpg","datePublished":"2021-12-06T08:30:59+00:00","dateModified":"2025-04-07T08:13:38+00:00","author":{"@id":"https:\/\/nimd.org\/fr\/#\/schema\/person\/fecd680c201ede81b56eb098a17ad928"},"breadcrumb":{"@id":"https:\/\/nimd.org\/mozambique-using-dialogue-in-the-fight-against-climate-change\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/nimd.org\/mozambique-using-dialogue-in-the-fight-against-climate-change\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/nimd.org\/mozambique-using-dialogue-in-the-fight-against-climate-change\/#primaryimage","url":"https:\/\/nimd.org\/wp-content\/uploads\/2025\/04\/UN744657_d4e_.jpg","contentUrl":"https:\/\/nimd.org\/wp-content\/uploads\/2025\/04\/UN744657_d4e_.jpg","width":1200,"height":800},{"@type":"BreadcrumbList","@id":"https:\/\/nimd.org\/mozambique-using-dialogue-in-the-fight-against-climate-change\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/nimd.org\/fr\/"},{"@type":"ListItem","position":2,"name":"Mozambique: Using dialogue in the fight against climate change"}]},{"@type":"WebSite","@id":"https:\/\/nimd.org\/fr\/#website","url":"https:\/\/nimd.org\/fr\/","name":"NIMD","description":"La democracia empieza por el di\u00e1logo","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/nimd.org\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/nimd.org\/fr\/#\/schema\/person\/fecd680c201ede81b56eb098a17ad928","name":"superadmin","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/1d1e7ebaf312b717161d349f71f6060e0ed86d7a652cbc37adc644a79988d181?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/1d1e7ebaf312b717161d349f71f6060e0ed86d7a652cbc37adc644a79988d181?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/1d1e7ebaf312b717161d349f71f6060e0ed86d7a652cbc37adc644a79988d181?s=96&d=mm&r=g","caption":"superadmin"}}]}},"_links":{"self":[{"href":"https:\/\/nimd.org\/es\/wp-json\/wp\/v2\/posts\/18984","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nimd.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nimd.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nimd.org\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/nimd.org\/es\/wp-json\/wp\/v2\/comments?post=18984"}],"version-history":[{"count":4,"href":"https:\/\/nimd.org\/es\/wp-json\/wp\/v2\/posts\/18984\/revisions"}],"predecessor-version":[{"id":25009,"href":"https:\/\/nimd.org\/es\/wp-json\/wp\/v2\/posts\/18984\/revisions\/25009"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nimd.org\/es\/wp-json\/wp\/v2\/media\/25010"}],"wp:attachment":[{"href":"https:\/\/nimd.org\/es\/wp-json\/wp\/v2\/media?parent=18984"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nimd.org\/es\/wp-json\/wp\/v2\/categories?post=18984"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nimd.org\/es\/wp-json\/wp\/v2\/tags?post=18984"},{"taxonomy":"countries","embeddable":true,"href":"https:\/\/nimd.org\/es\/wp-json\/wp\/v2\/countries?post=18984"},{"taxonomy":"theme","embeddable":true,"href":"https:\/\/nimd.org\/es\/wp-json\/wp\/v2\/theme?post=18984"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}