{"id":18726,"date":"2018-09-06T11:56:06","date_gmt":"2018-09-06T11:56:06","guid":{"rendered":"https:\/\/nimd.org\/60-ethiopian-political-parties-come-together-for-dialogue-in-adama\/"},"modified":"2025-04-07T08:00:28","modified_gmt":"2025-04-07T08:00:28","slug":"60-ethiopian-political-parties-come-together-for-dialogue-in-adama","status":"publish","type":"post","link":"https:\/\/nimd.org\/es\/60-ethiopian-political-parties-come-together-for-dialogue-in-adama\/","title":{"rendered":"60 partidos pol\u00edticos et\u00edopes se re\u00fanen para dialogar en Adama"},"content":{"rendered":"<p>El NIMD, junto con la Junta Electoral Nacional de Etiop\u00eda (NEBE), imparti\u00f3 formaci\u00f3n sobre di\u00e1logo y resoluci\u00f3n de conflictos a m\u00e1s de 60 de los 70 partidos pol\u00edticos registrados en Etiop\u00eda. Los delegados eran altos representantes de partidos nacionales y regionales, e inclu\u00edan a miembros de la alianza gobernante EPRDF y de partidos pol\u00edticos de la oposici\u00f3n. La formaci\u00f3n tuvo lugar en Adama los d\u00edas 27 y 28 de agosto y de nuevo los d\u00edas 30 y 31 de agosto de 2018. Esta fue la primera de muchas actividades previstas para los partidos pol\u00edticos despu\u00e9s de que el NIMD y el NEBE firmaran un Memorando de Entendimiento a principios de este a\u00f1o.<\/p>\n<p>Para que cualquier naci\u00f3n disfrute de un desarrollo sostenible, es fundamental una cultura pol\u00edtica que aproveche el di\u00e1logo entre las partes enfrentadas. Permite que los desacuerdos se resuelvan abiertamente, fomenta el compromiso pac\u00edfico y evita cualquier escalada hacia una pol\u00edtica de confrontaci\u00f3n. Esto, a su vez, ayuda a los gobiernos a ser \u00f3rganos representativos eficientes con los que los ciudadanos pueden hablar abiertamente de sus aspiraciones para el pa\u00eds. Al unir a tantas partes de Etiop\u00eda a trav\u00e9s del di\u00e1logo, el camino hacia el desarrollo sostenible est\u00e1 m\u00e1s claro para todos.<\/p>\n<p>La Presidenta del NEBE, la Embajadora Samia Gutu, inaugur\u00f3 la primera ronda de formaci\u00f3n y subray\u00f3 la importancia de que los partidos pol\u00edticos mejoren su capacidad para resolver conflictos y entablar un di\u00e1logo en esta coyuntura tan emocionante y cr\u00edtica de la historia del pa\u00eds. Adem\u00e1s, pidi\u00f3 una colaboraci\u00f3n m\u00e1s estrecha entre el NEBE y los partidos pol\u00edticos y les pidi\u00f3 que eligieran a cuatro personas de entre ellos para trabajar con el NEBE en la elaboraci\u00f3n de sugerencias para la reforma del NEBE.<\/p>\n<figure id=\"attachment_6749\" aria-describedby=\"caption-attachment-6749\" style=\"width: 512px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-6749\" src=\"http:\/\/nimd.org\/wp-content\/uploads\/2025\/04\/lesson.jpg\" alt=\"\" width=\"512\" height=\"248\" \/><figcaption id=\"caption-attachment-6749\" class=\"wp-caption-text\">Eugene van Kemenade dirige la formaci\u00f3n en Adama<\/figcaption><\/figure>\n<p>&nbsp;<\/p>\n<p>El formador, Eugene van Kemenade, imprimi\u00f3 a los delegados un estilo de formaci\u00f3n vivo e interactivo que les obligaba constantemente a poner en pr\u00e1ctica los conceptos y t\u00e9cnicas que iban aprendiendo. Aunque la formaci\u00f3n proporcion\u00f3 t\u00e9cnicas para la resoluci\u00f3n de conflictos, tambi\u00e9n hizo hincapi\u00e9 en la primac\u00eda del di\u00e1logo sobre todas las dem\u00e1s modalidades a la hora de intentar resolver los conflictos de forma pac\u00edfica.<\/p>\n<p>Al t\u00e9rmino de la formaci\u00f3n, los delegados valoraron positivamente los conocimientos adquiridos y manifestaron su inter\u00e9s por llevar lo aprendido a sus partidos para compartirlos; pidieron a NIMD que celebrara este tipo de formaciones con regularidad. Tambi\u00e9n valoraron positivamente el hecho de que la formaci\u00f3n hubiera proporcionado un espacio para que los distintos partidos pol\u00edticos se reunieran y conversaran entre s\u00ed.<\/p>","protected":false},"excerpt":{"rendered":"<p>El NIMD, junto con la Junta Electoral Nacional de Etiop\u00eda (NEBE), imparti\u00f3 formaci\u00f3n sobre di\u00e1logo y resoluci\u00f3n de conflictos a m\u00e1s de 60 de los 70 partidos pol\u00edticos registrados en Etiop\u00eda. Los delegados eran altos representantes de partidos tanto nacionales como regionales, e inclu\u00edan miembros de la alianza gobernante EPRDF, as\u00ed como de partidos pol\u00edticos de la oposici\u00f3n. ... <a href=\"https:\/\/nimd.org\/es\/60-ethiopian-political-parties-come-together-for-dialogue-in-adama\/\"><\/a><\/p>","protected":false},"author":2,"featured_media":22403,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[99],"tags":[],"countries":[83],"theme":[],"class_list":["post-18726","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","countries-ethiopia"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.5 (Yoast SEO v27.5) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>60 Ethiopian political parties come together for dialogue in Adama - NIMD<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/nimd.org\/es\/60-ethiopian-political-parties-come-together-for-dialogue-in-adama\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"60 Ethiopian political parties come together for dialogue in Adama\" \/>\n<meta property=\"og:description\" content=\"NIMD, in conjunction with the National Electoral Board of Ethiopia (NEBE), provided training for more than 60 of the 70 registered political parties in Ethiopia, on dialogue and conflict resolution. The delegates were senior party representatives of both national and regional parties and included members of the governing EPRDF alliance as well opposition political parties. &hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/nimd.org\/es\/60-ethiopian-political-parties-come-together-for-dialogue-in-adama\/\" \/>\n<meta property=\"og:site_name\" content=\"NIMD\" \/>\n<meta property=\"article:published_time\" content=\"2018-09-06T11:56:06+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-04-07T08:00:28+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/nimd.org\/wp-content\/uploads\/2025\/02\/argument.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"960\" \/>\n\t<meta property=\"og:image:height\" content=\"927\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"superadmin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"superadmin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/nimd.org\\\/60-ethiopian-political-parties-come-together-for-dialogue-in-adama\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/nimd.org\\\/60-ethiopian-political-parties-come-together-for-dialogue-in-adama\\\/\"},\"author\":{\"name\":\"superadmin\",\"@id\":\"https:\\\/\\\/nimd.org\\\/fr\\\/#\\\/schema\\\/person\\\/fecd680c201ede81b56eb098a17ad928\"},\"headline\":\"60 Ethiopian political parties come together for dialogue in Adama\",\"datePublished\":\"2018-09-06T11:56:06+00:00\",\"dateModified\":\"2025-04-07T08:00:28+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/nimd.org\\\/60-ethiopian-political-parties-come-together-for-dialogue-in-adama\\\/\"},\"wordCount\":391,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/nimd.org\\\/60-ethiopian-political-parties-come-together-for-dialogue-in-adama\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/nimd.org\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/argument.jpg\",\"articleSection\":[\"News\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/nimd.org\\\/60-ethiopian-political-parties-come-together-for-dialogue-in-adama\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/nimd.org\\\/60-ethiopian-political-parties-come-together-for-dialogue-in-adama\\\/\",\"url\":\"https:\\\/\\\/nimd.org\\\/60-ethiopian-political-parties-come-together-for-dialogue-in-adama\\\/\",\"name\":\"60 Ethiopian political parties come together for dialogue in Adama - NIMD\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/nimd.org\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/nimd.org\\\/60-ethiopian-political-parties-come-together-for-dialogue-in-adama\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/nimd.org\\\/60-ethiopian-political-parties-come-together-for-dialogue-in-adama\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/nimd.org\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/argument.jpg\",\"datePublished\":\"2018-09-06T11:56:06+00:00\",\"dateModified\":\"2025-04-07T08:00:28+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/nimd.org\\\/fr\\\/#\\\/schema\\\/person\\\/fecd680c201ede81b56eb098a17ad928\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/nimd.org\\\/60-ethiopian-political-parties-come-together-for-dialogue-in-adama\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/nimd.org\\\/60-ethiopian-political-parties-come-together-for-dialogue-in-adama\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/nimd.org\\\/60-ethiopian-political-parties-come-together-for-dialogue-in-adama\\\/#primaryimage\",\"url\":\"https:\\\/\\\/nimd.org\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/argument.jpg\",\"contentUrl\":\"https:\\\/\\\/nimd.org\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/argument.jpg\",\"width\":960,\"height\":927},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/nimd.org\\\/60-ethiopian-political-parties-come-together-for-dialogue-in-adama\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/nimd.org\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"60 Ethiopian political parties come together for dialogue in Adama\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/nimd.org\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/nimd.org\\\/fr\\\/\",\"name\":\"NIMD\",\"description\":\"Democracy Starts With Dialogue\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/nimd.org\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/nimd.org\\\/fr\\\/#\\\/schema\\\/person\\\/fecd680c201ede81b56eb098a17ad928\",\"name\":\"superadmin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1d1e7ebaf312b717161d349f71f6060e0ed86d7a652cbc37adc644a79988d181?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1d1e7ebaf312b717161d349f71f6060e0ed86d7a652cbc37adc644a79988d181?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1d1e7ebaf312b717161d349f71f6060e0ed86d7a652cbc37adc644a79988d181?s=96&d=mm&r=g\",\"caption\":\"superadmin\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"60 partidos pol\u00edticos et\u00edopes se re\u00fanen para dialogar en Adama - NIMD","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/nimd.org\/es\/60-ethiopian-political-parties-come-together-for-dialogue-in-adama\/","og_locale":"es_ES","og_type":"article","og_title":"60 Ethiopian political parties come together for dialogue in Adama","og_description":"NIMD, in conjunction with the National Electoral Board of Ethiopia (NEBE), provided training for more than 60 of the 70 registered political parties in Ethiopia, on dialogue and conflict resolution. The delegates were senior party representatives of both national and regional parties and included members of the governing EPRDF alliance as well opposition political parties. &hellip;","og_url":"https:\/\/nimd.org\/es\/60-ethiopian-political-parties-come-together-for-dialogue-in-adama\/","og_site_name":"NIMD","article_published_time":"2018-09-06T11:56:06+00:00","article_modified_time":"2025-04-07T08:00:28+00:00","og_image":[{"width":960,"height":927,"url":"https:\/\/nimd.org\/wp-content\/uploads\/2025\/02\/argument.jpg","type":"image\/jpeg"}],"author":"superadmin","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"superadmin","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/nimd.org\/60-ethiopian-political-parties-come-together-for-dialogue-in-adama\/#article","isPartOf":{"@id":"https:\/\/nimd.org\/60-ethiopian-political-parties-come-together-for-dialogue-in-adama\/"},"author":{"name":"superadmin","@id":"https:\/\/nimd.org\/fr\/#\/schema\/person\/fecd680c201ede81b56eb098a17ad928"},"headline":"60 Ethiopian political parties come together for dialogue in Adama","datePublished":"2018-09-06T11:56:06+00:00","dateModified":"2025-04-07T08:00:28+00:00","mainEntityOfPage":{"@id":"https:\/\/nimd.org\/60-ethiopian-political-parties-come-together-for-dialogue-in-adama\/"},"wordCount":391,"commentCount":0,"image":{"@id":"https:\/\/nimd.org\/60-ethiopian-political-parties-come-together-for-dialogue-in-adama\/#primaryimage"},"thumbnailUrl":"https:\/\/nimd.org\/wp-content\/uploads\/2025\/02\/argument.jpg","articleSection":["News"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/nimd.org\/60-ethiopian-political-parties-come-together-for-dialogue-in-adama\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/nimd.org\/60-ethiopian-political-parties-come-together-for-dialogue-in-adama\/","url":"https:\/\/nimd.org\/60-ethiopian-political-parties-come-together-for-dialogue-in-adama\/","name":"60 partidos pol\u00edticos et\u00edopes se re\u00fanen para dialogar en Adama - NIMD","isPartOf":{"@id":"https:\/\/nimd.org\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/nimd.org\/60-ethiopian-political-parties-come-together-for-dialogue-in-adama\/#primaryimage"},"image":{"@id":"https:\/\/nimd.org\/60-ethiopian-political-parties-come-together-for-dialogue-in-adama\/#primaryimage"},"thumbnailUrl":"https:\/\/nimd.org\/wp-content\/uploads\/2025\/02\/argument.jpg","datePublished":"2018-09-06T11:56:06+00:00","dateModified":"2025-04-07T08:00:28+00:00","author":{"@id":"https:\/\/nimd.org\/fr\/#\/schema\/person\/fecd680c201ede81b56eb098a17ad928"},"breadcrumb":{"@id":"https:\/\/nimd.org\/60-ethiopian-political-parties-come-together-for-dialogue-in-adama\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/nimd.org\/60-ethiopian-political-parties-come-together-for-dialogue-in-adama\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/nimd.org\/60-ethiopian-political-parties-come-together-for-dialogue-in-adama\/#primaryimage","url":"https:\/\/nimd.org\/wp-content\/uploads\/2025\/02\/argument.jpg","contentUrl":"https:\/\/nimd.org\/wp-content\/uploads\/2025\/02\/argument.jpg","width":960,"height":927},{"@type":"BreadcrumbList","@id":"https:\/\/nimd.org\/60-ethiopian-political-parties-come-together-for-dialogue-in-adama\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/nimd.org\/fr\/"},{"@type":"ListItem","position":2,"name":"60 Ethiopian political parties come together for dialogue in Adama"}]},{"@type":"WebSite","@id":"https:\/\/nimd.org\/fr\/#website","url":"https:\/\/nimd.org\/fr\/","name":"NIMD","description":"La democracia empieza por el di\u00e1logo","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/nimd.org\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/nimd.org\/fr\/#\/schema\/person\/fecd680c201ede81b56eb098a17ad928","name":"superadmin","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/1d1e7ebaf312b717161d349f71f6060e0ed86d7a652cbc37adc644a79988d181?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/1d1e7ebaf312b717161d349f71f6060e0ed86d7a652cbc37adc644a79988d181?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/1d1e7ebaf312b717161d349f71f6060e0ed86d7a652cbc37adc644a79988d181?s=96&d=mm&r=g","caption":"superadmin"}}]}},"_links":{"self":[{"href":"https:\/\/nimd.org\/es\/wp-json\/wp\/v2\/posts\/18726","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nimd.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nimd.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nimd.org\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/nimd.org\/es\/wp-json\/wp\/v2\/comments?post=18726"}],"version-history":[{"count":5,"href":"https:\/\/nimd.org\/es\/wp-json\/wp\/v2\/posts\/18726\/revisions"}],"predecessor-version":[{"id":24573,"href":"https:\/\/nimd.org\/es\/wp-json\/wp\/v2\/posts\/18726\/revisions\/24573"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nimd.org\/es\/wp-json\/wp\/v2\/media\/22403"}],"wp:attachment":[{"href":"https:\/\/nimd.org\/es\/wp-json\/wp\/v2\/media?parent=18726"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nimd.org\/es\/wp-json\/wp\/v2\/categories?post=18726"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nimd.org\/es\/wp-json\/wp\/v2\/tags?post=18726"},{"taxonomy":"countries","embeddable":true,"href":"https:\/\/nimd.org\/es\/wp-json\/wp\/v2\/countries?post=18726"},{"taxonomy":"theme","embeddable":true,"href":"https:\/\/nimd.org\/es\/wp-json\/wp\/v2\/theme?post=18726"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}